{"id":2023,"date":"2023-12-23T13:42:57","date_gmt":"2023-12-23T13:42:57","guid":{"rendered":"https:\/\/demo.webilia.com\/listdom\/?page_id=2023"},"modified":"2024-07-26T12:45:54","modified_gmt":"2024-07-26T12:45:54","slug":"square-markers","status":"publish","type":"page","link":"https:\/\/demo.webilia.com\/listdom\/advanced-map-addon\/square-markers\/","title":{"rendered":"Square Markers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2023\" class=\"elementor elementor-2023\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c636ac3 e-flex e-con-boxed e-con e-parent\" data-id=\"c636ac3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-84d248f e-con-full e-flex e-con e-child\" data-id=\"84d248f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd821de elementor-widget elementor-widget-heading\" data-id=\"cd821de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Square Markers<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e04f48 elementor-widget elementor-widget-button\" data-id=\"0e04f48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/webilia.com\/products\/listdom-advanced-map-addon\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Advanced Map Addon<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbd21e9 elementor-widget elementor-widget-text-editor\" data-id=\"bbd21e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \"><div class=\"wpb_wrapper\"><h2>Advanced Map Listing<\/h2><\/div><\/div><div class=\"wpb_text_column wpb_content_element  vc_custom_1659684293736\"><div class=\"wpb_wrapper\"><p>With this tool, you can display your listed items with square shape markers. This tool is fully customizable on the Listdom plugin classifieds WordPress.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd5adb0 elementor-widget elementor-widget-spacer\" data-id=\"cd5adb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e61e26e elementor-widget elementor-widget-shortcode\" data-id=\"e61e26e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"lsd-skin-wrapper lsd-singlemap-view-wrapper  \" id=\"lsd_skin2093\">\n    \n    <div class=\"lsd-skin-main-bar-wrapper\">\n        \n        <div class=\"lsd-singlemap-wrapper \" style=\"height: 500px;\">\n                        <div class=\"lsd-map-wrapper\">\n                <div class=\"lsd-listing-googlemap\">\n    <div id=\"lsd_map2093\" class=\"lsd-map-canvas\" style=\"height: 500px;\"><\/div>\n\n    \n<\/div>\n            <\/div>\n        <\/div>\n\n            <\/div>\n\n    <\/div>\n\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7c608b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c7c608b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/webilia.com\/products\/listdom-advanced-map-addon\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Add Advanced Map Addon to Listdom<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Advanced Map Addon Advanced Map Listing With this tool, you can display your listed items with square shape markers. This tool is fully customizable on the Listdom plugin classifieds WordPress. Add Advanced Map Addon to Listdom<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1212,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2023","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/pages\/2023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/comments?post=2023"}],"version-history":[{"count":22,"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/pages\/2023\/revisions"}],"predecessor-version":[{"id":6198,"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/pages\/2023\/revisions\/6198"}],"up":[{"embeddable":true,"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/pages\/1212"}],"wp:attachment":[{"href":"https:\/\/demo.webilia.com\/listdom\/wp-json\/wp\/v2\/media?parent=2023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}